{"id":24845,"date":"2020-04-29T11:08:39","date_gmt":"2020-04-29T09:08:39","guid":{"rendered":"https:\/\/www.campingdelmar.com\/animacio\/"},"modified":"2023-07-02T08:14:51","modified_gmt":"2023-07-02T06:14:51","slug":"animacio","status":"publish","type":"page","link":"https:\/\/www.campingdelmar.com\/ca\/animacio\/","title":{"rendered":"Animaci\u00f3"},"content":{"rendered":"\n<h1 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#82a4d5\">Animaci\u00f3<\/h1>\n\n<p class=\"has-text-align-center\">Volem que ho passis <strong>genial <\/strong>durant les teves vacances i per aix\u00f2 tenim programades <strong>molt\u00edssimes activitats<\/strong>. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una <strong>infinitat de coses m\u00e9s<\/strong>, que faran que la teva estada sigui <strong>inoblidable<\/strong>.<\/p>\n<style>\n.tag-img {\n    width: 80px;\n    height: 80px;\n    margin: 10px;\n    background-size: 40px 40px;\n    background-repeat: no-repeat;\n    background-position: center;\n    background-color: #e4eaec;\n    border: 4px solid #e4eaec;\n    border-radius: 50%;\n}\n#icons-block_ddcf6a4eecc2d943026fea58e3e2da7b .icon-wrap {\n    width: calc(100% \/ 6);\n}\n#icons-block_ddcf6a4eecc2d943026fea58e3e2da7b.is-style-accommodation .icon-wrap{\n    width: calc(100% \/ 6);\n}\n.is-style-accommodation .icons-wrapper{\n    justify-content: center;\n}\n.icon-wrap{\n    display: flex;\n    justify-content: center;\n    flex-wrap: wrap;\n    align-content: flex-start;\n}\n.icons-wrapper {\n    display: flex;\n    flex-wrap: wrap;\n    padding: 20px 10px;\n    font-family: 'Catamaran', sans-serif;\n}\n.tag-title {\n    width: 100%;\n    text-align: center;\n    font-weight: 300;\n    font-size: 14px;\n    text-transform: uppercase;\n    font-family: 'Catamaran', sans-serif;\n    padding-left: 2px;\n    padding-right: 2px;\n}\n.tag-description, .tag-description p{\n    width: 100%;\n    text-align: center;\n    font-size: 12px;\n    padding: 5px;\n    color: gray;\n    letter-spacing: 1px;\n    font-family: 'Catamaran', sans-serif;\n}\n.is-style-accommodation .icon-wrap .tag-img {\n    background-color: transparent;\n    border-color: transparent;\n}\n<\/style>\n\n<article id=\"icons-block_ddcf6a4eecc2d943026fea58e3e2da7b\" class=\"is-style-default\" >\n   <div class=\"inner-content \">\n\n                     <div class=\"icons-wrapper\">\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/stadium.svg)\"><\/div>\n                    <div class=\"tag-title\">Activitats esportives<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/swimming-pool-1.svg)\"><\/div>\n                    <div class=\"tag-title\">Aquagym<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/painting.svg)\"><\/div>\n                    <div class=\"tag-title\">Manualitats<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/party.svg)\"><\/div>\n                    <div class=\"tag-title\">Jocs i gincames<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/sax.svg)\"><\/div>\n                    <div class=\"tag-title\">M\u00fasica en viu<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/choreography.svg)\"><\/div>\n                    <div class=\"tag-title\">Classes de ball<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                        <\/div>\n            <\/div>\n\n<\/article>\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><!-- fold.php -->\n\n<style>\n\n<\/style>\n<script>\n    $(document).ready(function() {\n\n\n    });\n\n<\/script>\n    \n    <div id=\"fold-list-block_dd55c3b8f60e34187624fb0485500b94\" class=\"\">\n                <div class=\"fold-list-wrapper\">\n\n                                                <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-15\" name=\"faq-group\" checked>\n                <label for=\"faq-15\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/squid.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\u00a1Conoce a nuestra mascota Kala! <span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>La nostra mascota <strong>Kala<\/strong> \u00e9s un calamar especial. Va deixar la seva vida al mar i els seus companys calamars per encarregar-se de l&#8217;<strong>animaci\u00f3<\/strong> al C\u00e0mping del Mar.<\/p>\n<p>Amb els seus ajudants els <strong> animadors <\/ strong>, asseguren que la diversi\u00f3 sigui present durant les vostres vacances.<\/p>\n<p>Kala estar\u00e0 encantada de <strong> con\u00e8ixer-vos <\/ strong> aquest estiu!<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-16\" name=\"faq-group\" >\n                <label for=\"faq-16\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/painting.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Miniclub<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Al <strong>miniclub<\/strong>, els m\u00e9s petits podran <strong>jugar<\/strong>, dibuixar, <strong>crear<\/strong>, aprendre, pintar, compartir amb altres nens de tota Europa.<\/p>\n<p>A l&#8217;estiu i els caps de setmana en temporada baixa, el nostre equip d&#8217;<strong>animaci\u00f3<\/strong> prepara per a ells una infinitat d&#8217;<strong>activitats i jocs<\/strong> perqu\u00e8 s&#8217;ho passin genial !<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-17\" name=\"faq-group\" >\n                <label for=\"faq-17\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/team.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Activitats en fam\u00edlia<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Tamb\u00e9 pensem en vosaltres: els pares !<\/p>\n<p>Organitzem <strong>activitats per fer en fam\u00edlia <\/strong>i que pogueu gaudir tots junts!<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-18\" name=\"faq-group\" >\n                <label for=\"faq-18\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/stadium.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Activitats esportives<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Necessites una mica d&#8217;<strong>exercici<\/strong> durant les teves vacances?<\/p>\n<p>Cada dia et proposem una <strong>activitat<\/strong> diferent: paddlesurf, zumba, water polo, ping-pong, basquet, volei platja&#8230;<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-19\" name=\"faq-group\" >\n                <label for=\"faq-19\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/sax.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Espectacles nocturns<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Al C\u00e0mping del Mar, les nits s\u00f3n per <strong>relaxar-se<\/strong> i <strong>divertir-se<\/strong>.<\/p>\n<p>Les nits d&#8217;estiu cada dia hi ha una <strong>animaci\u00f3<\/strong> diferent al <strong>bar-restaurant<\/strong>. M\u00fasica en directe, espectacle de falmenc, bingo, Karaoke&#8230;<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-20\" name=\"faq-group\" >\n                <label for=\"faq-20\">Exemple de programa d&#8217;animaci\u00f3<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color has-blank-3-black-color\" href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-20190722-162634.jpg\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"image-link\" class=\"image-link\">Veure un exemple de programa d&#8217;animaci\u00f3<\/a><\/div>\n<\/div>\n\n<p><\/p>\n\n<\/div>\n                            <\/div>\n                    <\/div>\n        \n    <\/div>\n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n\n                    <style>\n\n\n        <\/style>\n        <article id=\"custom-gallery-block_623e53c31f3dac40536ed52dd2ae18df\" class=\"custom-gallery   is-style-rounded\" >\n                        \n            <script>\n            $(window).load(function() {\n\n\n                var slider = tns({\n                    nav: false,\n                    controls: true,\n                    container: '.id-gal106',\n                    items: 1,\n                    autoWidth: false,\n                    autoplay: false,\n                    mouseDrag: true,\n                    responsive: {\n                      0: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n                      400: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n\n                      600: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n                      900: {\n                        edgePadding: 0,\n                        items: 1,\n                        gutter: 0,\n                      }\n                    }\n                  });\n                });\n\n            <\/script><div class=\"galeria clearfix galeria-carousel id-gal106\"><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-1374-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5983-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6000-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-7324-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-7217-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mans-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/dscf9314-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-8612-1-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/futbol-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/pistas-deportivas-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5994-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/xthv8552-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/gzsg4699-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6848-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6858-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6376-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-7108-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0256-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0262-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0989-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0979-900x600.jpg)\"><\/div><\/div><\/div>        <\/article>\n\n\n\n    \n\n\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Animaci\u00f3 Volem que ho passis genial durant les teves vacances [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38241,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-24845","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e0mping amb animaci\u00f3 per nens<\/title>\n<meta name=\"description\" content=\"Animaci\u00f3 Volem que ho passis genial durant les teves vacances i per aix\u00f2 tenim programades molt\u00edssimes activitats. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campingdelmar.com\/ca\/animacio\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e0mping amb animaci\u00f3 per nens\" \/>\n<meta property=\"og:description\" content=\"Animaci\u00f3 Volem que ho passis genial durant les teves vacances i per aix\u00f2 tenim programades molt\u00edssimes activitats. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campingdelmar.com\/ca\/animacio\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping del Mar\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-02T06:14:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/\",\"name\":\"C\u00e0mping amb animaci\u00f3 per nens\",\"isPartOf\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg\",\"datePublished\":\"2020-04-29T09:08:39+00:00\",\"dateModified\":\"2023-07-02T06:14:51+00:00\",\"description\":\"Animaci\u00f3 Volem que ho passis genial durant les teves vacances i per aix\u00f2 tenim programades molt\u00edssimes activitats. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una\",\"breadcrumb\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campingdelmar.com\/ca\/animacio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/#primaryimage\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/animacio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.campingdelmar.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animaci\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#website\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/\",\"name\":\"Camping del Mar\",\"description\":\"Bungalow Park, Malgrat de Mar\",\"publisher\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campingdelmar.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#organization\",\"name\":\"Camping del Mar\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"width\":619,\"height\":697,\"caption\":\"Camping del Mar\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e0mping amb animaci\u00f3 per nens","description":"Animaci\u00f3 Volem que ho passis genial durant les teves vacances i per aix\u00f2 tenim programades molt\u00edssimes activitats. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campingdelmar.com\/ca\/animacio\/","og_locale":"ca_ES","og_type":"article","og_title":"C\u00e0mping amb animaci\u00f3 per nens","og_description":"Animaci\u00f3 Volem que ho passis genial durant les teves vacances i per aix\u00f2 tenim programades molt\u00edssimes activitats. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una","og_url":"https:\/\/www.campingdelmar.com\/ca\/animacio\/","og_site_name":"Camping del Mar","article_modified_time":"2023-07-02T06:14:51+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.campingdelmar.com\/ca\/animacio\/","url":"https:\/\/www.campingdelmar.com\/ca\/animacio\/","name":"C\u00e0mping amb animaci\u00f3 per nens","isPartOf":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campingdelmar.com\/ca\/animacio\/#primaryimage"},"image":{"@id":"https:\/\/www.campingdelmar.com\/ca\/animacio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg","datePublished":"2020-04-29T09:08:39+00:00","dateModified":"2023-07-02T06:14:51+00:00","description":"Animaci\u00f3 Volem que ho passis genial durant les teves vacances i per aix\u00f2 tenim programades molt\u00edssimes activitats. Ballar\u00e0s, saltar\u00e0s, far\u00e0s esport i una","breadcrumb":{"@id":"https:\/\/www.campingdelmar.com\/ca\/animacio\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campingdelmar.com\/ca\/animacio\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.campingdelmar.com\/ca\/animacio\/#primaryimage","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-6316-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.campingdelmar.com\/ca\/animacio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.campingdelmar.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Animaci\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/www.campingdelmar.com\/ca\/#website","url":"https:\/\/www.campingdelmar.com\/ca\/","name":"Camping del Mar","description":"Bungalow Park, Malgrat de Mar","publisher":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campingdelmar.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.campingdelmar.com\/ca\/#organization","name":"Camping del Mar","url":"https:\/\/www.campingdelmar.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","width":619,"height":697,"caption":"Camping del Mar"},"image":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/comments?post=24845"}],"version-history":[{"count":11,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24845\/revisions"}],"predecessor-version":[{"id":48876,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24845\/revisions\/48876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/media\/38241"}],"wp:attachment":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/media?parent=24845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}