{"id":24869,"date":"2020-04-29T11:26:18","date_gmt":"2020-04-29T09:26:18","guid":{"rendered":"https:\/\/www.campingdelmar.com\/parcelles\/"},"modified":"2026-02-05T11:22:27","modified_gmt":"2026-02-05T10:22:27","slug":"parcelles","status":"publish","type":"page","link":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/","title":{"rendered":"Parcel\u00b7les"},"content":{"rendered":"<style>\n.tag-img {\n    width: 80px;\n    height: 80px;\n    margin: 10px;\n    background-size: 40px 40px;\n    background-repeat: no-repeat;\n    background-position: center;\n    background-color: #e4eaec;\n    border: 4px solid #e4eaec;\n    border-radius: 50%;\n}\n#icons-block_c99d7dae83e892afcf8a8fbecc22376b .icon-wrap {\n    width: calc(100% \/ 5);\n}\n#icons-block_c99d7dae83e892afcf8a8fbecc22376b.is-style-accommodation .icon-wrap{\n    width: calc(100% \/ 8);\n}\n.is-style-accommodation .icons-wrapper{\n    justify-content: center;\n}\n.icon-wrap{\n    display: flex;\n    justify-content: center;\n    flex-wrap: wrap;\n    align-content: flex-start;\n}\n.icons-wrapper {\n    display: flex;\n    flex-wrap: wrap;\n    padding: 20px 10px;\n    font-family: 'Catamaran', sans-serif;\n}\n.tag-title {\n    width: 100%;\n    text-align: center;\n    font-weight: 300;\n    font-size: 14px;\n    text-transform: uppercase;\n    font-family: 'Catamaran', sans-serif;\n    padding-left: 2px;\n    padding-right: 2px;\n}\n.tag-description, .tag-description p{\n    width: 100%;\n    text-align: center;\n    font-size: 12px;\n    padding: 5px;\n    color: gray;\n    letter-spacing: 1px;\n    font-family: 'Catamaran', sans-serif;\n}\n.is-style-accommodation .icon-wrap .tag-img {\n    background-color: transparent;\n    border-color: transparent;\n}\n<\/style>\n\n<article id=\"icons-block_c99d7dae83e892afcf8a8fbecc22376b\" class=\"is-style-accommodation\" >\n   <div class=\"inner-content \">\n\n                     <div class=\"icons-wrapper\">\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/icon-people-01.svg)\"><\/div>\n                    <div class=\"tag-title\">6 persones<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/area.svg)\"><\/div>\n                    <div class=\"tag-title\">64m2<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/thunderbolt.svg)\"><\/div>\n                    <div class=\"tag-title\">6 amp<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/fridge.svg)\"><\/div>\n                    <div class=\"tag-title\">Lloguer de neveres<\/div>\n                    <div class=\"tag-description\">\n                        <p><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/ce4ec7da-6675-4e02-bcec-bfbba3e611eb.pdf\">Ver tarifas<\/a><\/p>\n                    <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                        <\/div>\n            <\/div>\n\n<\/article>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#82a4d5\">Les nostres parcel\u00b7les<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Gaudeix de les teves vacances a les nostres parcel\u00b7les amb gespa, ben delimitades i numerades. Totes elles ocupen al voltant de 64m<sup>2<\/sup> i tenen conexi\u00f3 el\u00e8ctrica 6A.<\/p>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><!-- fold.php -->\n\n<style>\n\n<\/style>\n<script>\n    $(document).ready(function() {\n\n\n    });\n\n<\/script>\n    \n    <div id=\"fold-list-block_731164f0a2c77caa30e1b8ec189f2e99\" class=\"\">\n                <div class=\"fold-list-wrapper\">\n\n                                                <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-68\" name=\"faq-group\" checked>\n                <label for=\"faq-68\">Resum<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>Parcela de c\u00e9sped de 64m<sup>2 <\/sup>(8 x 8m)<\/li>\n<li>Parcela delimitada<\/li>\n<li>Conexi\u00f3n el\u00e9ctrica de 6 amp<\/li>\n<li>Sanitarios con ducha con agua caliente y ba\u00f1o.<br \/>\n<a href=\"https:\/\/www.campingdelmar.com\/ca\/installacions\/?f=24593\">Veure sanitaris.<\/a><\/li>\n<\/ul>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-69\" name=\"faq-group\" >\n                <label for=\"faq-69\">Serveis opcionals<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>Afegeix m\u00e9s diversi\u00f3 a la teva estada contractant a preu exclusiu els serveis de la <strong>base n\u00e0utica<\/strong> (Paddlesurf, Kayak, Windsurf) !<\/li>\n<li>Reserva el teu <strong>esmorzar<\/strong> i no et preocupis de res pels matins !<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>I tamb\u00e9\u2026<\/p>\n<ul>\n<li><strong>Wifi<\/strong> per compartir les teves vacances amb els teus amics i familiars<\/li>\n<li>Lloguer de <strong>neveres<\/strong> perqu\u00e8 la teva instal\u00b7laci\u00f3 sigui m\u00e9s f\u00e0cil<\/li>\n<li>Lloguer de <strong>bicicletes<\/strong> per a tots els que no paren mai<\/li>\n<li>Contractaci\u00f3 d&#8217;<strong>asseguran\u00e7a de cancelaci\u00f3<\/strong> per als mes previnguts<br \/>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-custom\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/12-condicionado-seguro-de-reservas-temporal-catalan.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Veure les condicions generals de la p\u00f2lissa d&#8217;assegurances<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-70\" name=\"faq-group\" >\n                <label for=\"faq-70\">Condicions<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>S&#8217;admeten animals, sempre i quan no siguin considerats de ra\u00e7a potencialment perillosa. <a href=\"https:\/\/www.boe.es\/boe\/dias\/2002\/03\/27\/pdfs\/A12290-12292.pdf\">Veure clasificaci\u00f3 oficial.<\/a><\/li>\n<\/ul>\n<\/div>\n                            <\/div>\n                    <\/div>\n        \n    <\/div>\n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n\n                    <style>\n\n\n        <\/style>\n        <article id=\"custom-gallery-block_e15f6370399b110a751b7034fd8e4096\" class=\"custom-gallery   is-style-rounded\" >\n                        \n            <script>\n            $(window).load(function() {\n\n\n                var slider = tns({\n                    nav: false,\n                    controls: true,\n                    container: '.id-gal566',\n                    items: 1,\n                    autoWidth: false,\n                    autoplay: false,\n                    mouseDrag: true,\n                    responsive: {\n                      0: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n                      400: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n\n                      600: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n                      900: {\n                        edgePadding: 0,\n                        items: 1,\n                        gutter: 0,\n                      }\n                    }\n                  });\n                });\n\n            <\/script><div class=\"galeria clearfix galeria-carousel id-gal566\"><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0160-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0178-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-0602-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/crc1016-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/crc1011-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5587-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-2327-1-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-2328-1-900x600.jpg)\"><\/div><\/div><div class=\"item-slider cover\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/p4140100-900x600.jpg)\"><\/div><\/div><\/div>        <\/article>\n\n\n\n    \n\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-custom\"><a class=\"wp-block-button__link has-blank-3-white-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.campingdelmar.com\/ca\/2020\/informacio\/en-furgoneta-per-catalunya-decobreix-la-proxima-etapa-del-teu-viatge\/\" style=\"border-radius:4px;color:#82a4d5\" target=\"_blank\" rel=\"noreferrer noopener\">Descobreix la tarifa Sleep&amp;Go<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-hidden is-style-custom\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/booking.campingdelmar.com\/search?lang=ca&amp;categoryIds=2\" style=\"border-radius:4px;background-color:#82a4d5\" target=\"_blank\" rel=\"noreferrer noopener\">Reservar ara<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-custom\"><a class=\"wp-block-button__link has-blank-3-white-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.campingdelmar.com\/ca\/2020\/ofertes\/parcelles-de-temporada\/\" style=\"border-radius:4px;color:#82a4d5\">Parcel\u00b7les de temporada<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\"><img decoding=\"async\" width=\"2048\" height=\"1125\" class=\"wp-block-cover__image-background wp-image-19437 lazyload\" alt=\"\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1.jpg\" data-object-fit=\"cover\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1.jpg 2048w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-300x165.jpg 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-1024x563.jpg 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-1536x844.jpg 1536w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-900x494.jpg 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-320x176.jpg 320w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-240x132.jpg 240w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-1800x989.jpg 1800w\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1125;\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-blank-3-white-background-color has-background-dim-90 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-blank-3-black-color has-text-color has-medium-font-size\" style=\"font-style:normal;font-weight:700\">Altres allotjaments que et poden interessar<\/h2>\n\n\n\n<style>\n@media only screen and (min-width: 0px) and (max-width: 380px){\n        #grid-items-block_1d05e1666881d1de0e42eb096ee050f5.is-style-default [class*=\"grid-item\"] {\n            flex-basis: 100%;\n            width: 100%;\n        }\n\n        #grid-items-block_1d05e1666881d1de0e42eb096ee050f5{\n            justify-content: center;\n        }\n    }\n@media only screen and (min-width: 381px) and (max-width: 799px){\n        #grid-items-block_1d05e1666881d1de0e42eb096ee050f5.is-style-default [class*=\"grid-item\"] {\n            flex-basis: 48%;\n            width: 48%;\n        }\n\n    }\n@media only screen and (min-width: 800px){\n        #grid-items-block_1d05e1666881d1de0e42eb096ee050f5 [class*=\"grid-item\"] {\n            width: calc(100% * (1\/3) - 1%);\n            margin: calc(2% *(1\/4));\n        }\n        #grid-items-block_1d05e1666881d1de0e42eb096ee050f5.is-style-dynamic [class*=\"grid-item\"]:hover{\n            width: calc(100% * (1\/2.25) - 1%);\n        }\n    }\n<\/style>\n<div class=\"wp-block-grid-items default\">\n    <div id=\"grid-items-block_1d05e1666881d1de0e42eb096ee050f5\" class=\"flex is-style-circles\">\n                <a class=\"grid-item-24921\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\">\n            <div class=\"inner-card\">\n                                                                <div id=\"thumbnail-19449\" class=\"thumbnail-card\">\n\n                                            <img decoding=\"async\" width=\"420\" height=\"270\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj-420x270.jpg\" class=\"attachment-carousel-small size-carousel-small wp-post-image lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 420px; --smush-placeholder-aspect-ratio: 420\/270;\" \/>                                    <\/div>\n                <div class=\"content-card html-content\">\n                    <h4 class=\"has-blank-3-new-blue-1-color\">Bungalow Premium                                                                   <\/h4>\n                                            <p>Pels amants del &#8220;tot incl\u00f2s&#8221;. Capacitat m\u00e0xima: 6 persones<\/p>\n                                    <\/div>\n            <\/div>\n\n\n        <\/a>\n                <a class=\"grid-item-24961\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-6-persones\/\">\n            <div class=\"inner-card\">\n                                                                <div id=\"thumbnail-19451\" class=\"thumbnail-card\">\n\n                                            <img decoding=\"async\" width=\"420\" height=\"270\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0245-420x270.jpg\" class=\"attachment-carousel-small size-carousel-small wp-post-image lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 420px; --smush-placeholder-aspect-ratio: 420\/270;\" \/>                                    <\/div>\n                <div class=\"content-card html-content\">\n                    <h4 class=\"has-blank-3-new-blue-1-color\">Mobil-Home 6 persones                                                                   <\/h4>\n                                            <p>Perqu\u00e8 tota la fam\u00edlia gaudeixi sense que els hi falti de res. Capacitat m\u00e0xima: 6 persones<\/p>\n                                    <\/div>\n            <\/div>\n\n\n        <\/a>\n                <a class=\"grid-item-39596\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/glamping-mar-4-persones\/\">\n            <div class=\"inner-card\">\n                                                                <div id=\"thumbnail-38974\" class=\"thumbnail-card\">\n\n                                            <img decoding=\"async\" width=\"420\" height=\"270\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/41-1-420x270.jpg\" class=\"attachment-carousel-small size-carousel-small wp-post-image lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 420px; --smush-placeholder-aspect-ratio: 420\/270;\" \/>                                    <\/div>\n                <div class=\"content-card html-content\">\n                    <h4 class=\"has-blank-3-new-blue-1-color\">Glamping Mar 4 persones                                                                   <\/h4>\n                                    <\/div>\n            <\/div>\n\n\n        <\/a>\n            <\/div>\n<\/div>\n\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pels amants del c\u00e0mping del tota la vida.<\/p>\n","protected":false},"author":1,"featured_media":42848,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-24869","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camping del Mar - Millor preu garantit! ????<\/title>\n<meta name=\"description\" content=\"Gaudeix de les teves vacances a les nostres parcel\u00b7les de 64m2 amb gespa, molt ben delimitades i amb connexi\u00f3 el\u00e8ctrica 6A.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camping del Mar - Millor preu garantit! ????\" \/>\n<meta property=\"og:description\" content=\"Gaudeix de les teves vacances a les nostres parcel\u00b7les de 64m2 amb gespa, molt ben delimitades i amb connexi\u00f3 el\u00e8ctrica 6A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping del Mar\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T10:22:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1916\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/\",\"name\":\"Camping del Mar - Millor preu garantit! ????\",\"isPartOf\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg\",\"datePublished\":\"2020-04-29T09:26:18+00:00\",\"dateModified\":\"2026-02-05T10:22:27+00:00\",\"description\":\"Gaudeix de les teves vacances a les nostres parcel\u00b7les de 64m2 amb gespa, molt ben delimitades i amb connexi\u00f3 el\u00e8ctrica 6A.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#primaryimage\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg\",\"width\":1916,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.campingdelmar.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parcel\u00b7les\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#website\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/\",\"name\":\"Camping del Mar\",\"description\":\"Bungalow Park, Malgrat de Mar\",\"publisher\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campingdelmar.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#organization\",\"name\":\"Camping del Mar\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"width\":619,\"height\":697,\"caption\":\"Camping del Mar\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camping del Mar - Millor preu garantit! ????","description":"Gaudeix de les teves vacances a les nostres parcel\u00b7les de 64m2 amb gespa, molt ben delimitades i amb connexi\u00f3 el\u00e8ctrica 6A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/","og_locale":"ca_ES","og_type":"article","og_title":"Camping del Mar - Millor preu garantit! ????","og_description":"Gaudeix de les teves vacances a les nostres parcel\u00b7les de 64m2 amb gespa, molt ben delimitades i amb connexi\u00f3 el\u00e8ctrica 6A.","og_url":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/","og_site_name":"Camping del Mar","article_modified_time":"2026-02-05T10:22:27+00:00","og_image":[{"width":1916,"height":1080,"url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/","url":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/","name":"Camping del Mar - Millor preu garantit! ????","isPartOf":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#primaryimage"},"image":{"@id":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg","datePublished":"2020-04-29T09:26:18+00:00","dateModified":"2026-02-05T10:22:27+00:00","description":"Gaudeix de les teves vacances a les nostres parcel\u00b7les de 64m2 amb gespa, molt ben delimitades i amb connexi\u00f3 el\u00e8ctrica 6A.","breadcrumb":{"@id":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campingdelmar.com\/ca\/parcelles\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#primaryimage","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/captura-de-pantalla-2023-01-27-091340-1.jpg","width":1916,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.campingdelmar.com\/ca\/parcelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.campingdelmar.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Parcel\u00b7les"}]},{"@type":"WebSite","@id":"https:\/\/www.campingdelmar.com\/ca\/#website","url":"https:\/\/www.campingdelmar.com\/ca\/","name":"Camping del Mar","description":"Bungalow Park, Malgrat de Mar","publisher":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campingdelmar.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.campingdelmar.com\/ca\/#organization","name":"Camping del Mar","url":"https:\/\/www.campingdelmar.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","width":619,"height":697,"caption":"Camping del Mar"},"image":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/comments?post=24869"}],"version-history":[{"count":13,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24869\/revisions"}],"predecessor-version":[{"id":54770,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24869\/revisions\/54770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/media\/42848"}],"wp:attachment":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/media?parent=24869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}