{"id":24921,"date":"2020-04-29T12:10:35","date_gmt":"2020-04-29T10:10:35","guid":{"rendered":"https:\/\/www.campingdelmar.com\/allotjaments\/bungalow-premium\/"},"modified":"2026-02-05T11:12:13","modified_gmt":"2026-02-05T10:12:13","slug":"bungalow-premium","status":"publish","type":"page","link":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/","title":{"rendered":"Bungalow Premium"},"content":{"rendered":"\n<div class=\"wp-block-cover is-light\" style=\"min-height:185px;aspect-ratio:unset;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" class=\"wp-block-cover__image-background wp-image-38917 lazyload\" alt=\"\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-scaled.jpg\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1708;object-position:60% 83%\" data-object-fit=\"cover\" data-object-position=\"60% 83%\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-scaled.jpg 2560w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-300x200.jpg 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-1024x683.jpg 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-1536x1025.jpg 1536w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-2048x1366.jpg 2048w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-900x600.jpg 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-90x60.jpg 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-240x160.jpg 240w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp65-1800x1201.jpg 1800w\" data-sizes=\"(max-width: 2560px) 100vw, 2560px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-blank-3-white-color has-text-color has-large-font-size\"><\/p>\n\n\n\n<p class=\"has-text-align-center has-blank-3-white-color has-text-color has-medium-font-size\"><\/p>\n<\/div><\/div>\n\n\n<style>\n.tag-img {\n    width: 80px;\n    height: 80px;\n    margin: 10px;\n    background-size: 40px 40px;\n    background-repeat: no-repeat;\n    background-position: center;\n    background-color: #e4eaec;\n    border: 4px solid #e4eaec;\n    border-radius: 50%;\n}\n#icons-block_30ec71ad87e62a82d9e1f91365e26883 .icon-wrap {\n    width: calc(100% \/ 5);\n}\n#icons-block_30ec71ad87e62a82d9e1f91365e26883.is-style-accommodation .icon-wrap{\n    width: calc(100% \/ 5);\n}\n.is-style-accommodation .icons-wrapper{\n    justify-content: center;\n}\n.icon-wrap{\n    display: flex;\n    justify-content: center;\n    flex-wrap: wrap;\n    align-content: flex-start;\n}\n.icons-wrapper {\n    display: flex;\n    flex-wrap: wrap;\n    padding: 20px 10px;\n    font-family: 'Catamaran', sans-serif;\n}\n.tag-title {\n    width: 100%;\n    text-align: center;\n    font-weight: 300;\n    font-size: 14px;\n    text-transform: uppercase;\n    font-family: 'Catamaran', sans-serif;\n    padding-left: 2px;\n    padding-right: 2px;\n}\n.tag-description, .tag-description p{\n    width: 100%;\n    text-align: center;\n    font-size: 12px;\n    padding: 5px;\n    color: gray;\n    letter-spacing: 1px;\n    font-family: 'Catamaran', sans-serif;\n}\n.is-style-accommodation .icon-wrap .tag-img {\n    background-color: transparent;\n    border-color: transparent;\n}\n<\/style>\n\n<article id=\"icons-block_30ec71ad87e62a82d9e1f91365e26883\" class=\"is-style-accommodation\" >\n   <div class=\"inner-content \">\n\n                     <div class=\"icons-wrapper\">\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/icon-people-01.svg)\"><\/div>\n                    <div class=\"tag-title\">6 persones<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/real-estate-01.svg)\"><\/div>\n                    <div class=\"tag-title\">27m2<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/parking.svg)\"><\/div>\n                    <div class=\"tag-title\">Pla\u00e7a de parking<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/dog-1-01.svg)\"><\/div>\n                    <div class=\"tag-title\">No s&#8217;admeten animals<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/terrace-01.svg)\"><\/div>\n                    <div class=\"tag-title\">Terrassa<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bbq-grill.svg)\"><\/div>\n                    <div class=\"tag-title\">Barbacoa inclosa<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/multimedia-01.svg)\"><\/div>\n                    <div class=\"tag-title\">Televisi\u00f3<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/air-conditioner-01.svg)\"><\/div>\n                    <div class=\"tag-title\">A\/C<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/towel.svg)\"><\/div>\n                    <div class=\"tag-title\">Llen\u00e7ols i tovalloles incloses<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                                                                            \n                <div class=\"icon-wrap\">\n                    <div class=\"tag-img lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/wifi.svg)\"><\/div>\n                    <div class=\"tag-title\">1 codi wifi gratis<\/div>\n                    <div class=\"tag-description\">\n                                            <\/div>\n                    <!--<div class=\"icon-tooltip\">\n                                            <\/div>-->\n\n                <\/div>\n                        <\/div>\n            <\/div>\n\n<\/article>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#82a4d5\">Bungalow Premium<\/h2>\n\n\n\n<p class=\"has-text-align-center\">El <strong>Bungalow Premium<\/strong> \u00e9s perfecte pels que volen un allotjament tot incl\u00f2s. T\u00e9 <strong>2 habitacions<\/strong> i un sof\u00e0-llit al menjador, una cuina equipada, una terrassa coberta amb barbacoa i una pla\u00e7a de parquing al costat del bungalow. El Bungalow Premium tamb\u00e9 compta amb <strong>aire acondicionat i calefacci\u00f3<\/strong>, els <strong>llen\u00e7ols i tovalloles incloses <\/strong>&nbsp;i un codi <strong>wifi gratis<\/strong> per a tota l&#8217;estada!<\/p>\n\n\n\n<p class=\"has-text-align-center\">Capacitat m\u00e0xima : <strong>6 persones<\/strong>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><!-- fold.php -->\n\n<style>\n\n<\/style>\n<script>\n    $(document).ready(function() {\n\n\n    });\n\n<\/script>\n    \n    <div id=\"fold-list-block_66157c579fbc6a52e18810bfeba331e6\" class=\"\">\n                <div class=\"fold-list-wrapper\">\n\n                                                <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-40\" name=\"faq-group\" checked>\n                <label for=\"faq-40\">Resum<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>Bungalow de fusta de 27m<sup>2<\/sup><\/li>\n<li>Capacitat m\u00e0xima: 6 persones<\/li>\n<li>2 habitacions<\/li>\n<li>Habitaci\u00f3 1: llit de matrimoni<\/li>\n<li>Habitaci\u00f3 2: 2 llits individuals<\/li>\n<li>Sof\u00e0-llit per 2 persones al menjador<\/li>\n<li>Cuina totalment equipada<\/li>\n<li>1 bany amb dutxa<\/li>\n<li>Aparcament per a 1 cotxe al costat del bungalow<\/li>\n<li>Terrassa coberta<\/li>\n<\/ul>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-41\" name=\"faq-group\" >\n                <label for=\"faq-41\">Equipament<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>Nevera<\/li>\n<li>Microoness<\/li>\n<li>Cafetera<\/li>\n<li>Vaixella<\/li>\n<li>&#8230;<\/li>\n<\/ul>\n<p>Descarrega l&#8217;inventari per a m\u00e9s informaci\u00f3.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bp-cat-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Veure inventari<\/a><\/div>\n<\/div>\n\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-42\" name=\"faq-group\" >\n                <label for=\"faq-42\">Serveis opcionals<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>Afegeix m\u00e9s diversi\u00f3 a la teva estada contractant a preu exclusiu els serveis de la <strong>base n\u00e0utica<\/strong> (Paddlesurf, Kayak, Windsurf) !<\/li>\n<li>Reserva el teu <strong>esmorzar<\/strong> i no et preocupis de res pels matins !<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>I tamb\u00e9&#8230;<\/p>\n<ul>\n<li><strong>Wifi<\/strong> per compartir les teves vacances amb els teus amics i familiars<\/li>\n<li>Servei de <strong>neteja final<\/strong> per gaudir de les teves vacances fins a l&#8217;\u00faltim minut<\/li>\n<li>Lloguer de <strong>llen\u00e7ols i tovalloles<\/strong> per alliberar espai al cotxe<\/li>\n<li>Lloguer de <strong>llitets i trones <\/strong>pels petits<\/li>\n<li>Lloguer de <strong>bicicletes<\/strong> pels que no paren mai<\/li>\n<li>Contractaci\u00f3 d&#8217;<strong>asseguran\u00e7a de cancelaci\u00f3<\/strong> per als m\u00e9s previsors<br \/>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-custom\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/12-condicionado-seguro-de-reservas-temporal-catalan.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Veure les condicions generals de la p\u00f2lissa d&#8217;assegurances<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-43\" name=\"faq-group\" >\n                <label for=\"faq-43\">Condicions<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><ul>\n<li>No s&#8217;admeten animals<\/li>\n<li>Els nadons i nens de totes les edats han de comptar-se en el cupo m\u00e0xim de 6 persones<\/li>\n<\/ul>\n<\/div>\n                            <\/div>\n                    <\/div>\n        \n    <\/div>\n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n\n                    <style>\n\n\n        <\/style>\n        <article id=\"custom-gallery-block_22da6ed718a2c82d4176b79cdeacba94\" class=\"custom-gallery   is-style-rounded\" >\n                        \n            <script>\n            $(window).load(function() {\n\n\n                var slider = tns({\n                    nav: false,\n                    controls: true,\n                    container: '.id-gal466',\n                    items: 1,\n                    autoWidth: false,\n                    autoplay: false,\n                    mouseDrag: true,\n                    responsive: {\n                      0: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n                      400: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n\n                      600: {\n                        edgePadding: 0,\n                        items: 1\n                      },\n                      900: {\n                        edgePadding: 0,\n                        items: 1,\n                        gutter: 0,\n                      }\n                    }\n                  });\n                });\n\n            <\/script><div class=\"galeria clearfix galeria-carousel id-gal466\"><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj-1800x1677.jpg\" id=\"thumb-35416\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0582-1800x1201.jpg\" id=\"thumb-35381\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0582-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0555-1800x1201.jpg\" id=\"thumb-35318\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0555-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0527-1800x1201.jpg\" id=\"thumb-35325\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0527-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0533-1800x1201.jpg\" id=\"thumb-35332\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0533-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0537-1800x1201.jpg\" id=\"thumb-35339\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0537-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0540-1800x1201.jpg\" id=\"thumb-35346\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0540-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0548-1800x1201.jpg\" id=\"thumb-35353\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0548-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0561-1800x1201.jpg\" id=\"thumb-35367\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0561-900x600.jpg)\"><\/div><\/a><\/div><div class=\"item-slider cover\"><a href=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0599-1800x1201.jpg\" id=\"thumb-35388\" class=\"image-link\"><div class=\"inner-image cover lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0599-900x600.jpg)\"><\/div><\/a><\/div><\/div>        <\/article>\n\n\n\n    \n\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-custom is-style-outline--2\"><a class=\"wp-block-button__link has-blank-3-white-background-color has-text-color has-background wp-element-button\" href=\"#popup-comparador\" style=\"color:#82a4d5\">Comparador<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-hidden is-style-custom\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/booking.campingdelmar.com\/search?lang=ca&amp;categoryIds=1\" style=\"background-color:#82a4d5\" target=\"_blank\" rel=\"noreferrer noopener\">Reservar ara<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link has-blank-3-white-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium-adaptat-2\/\" style=\"color:#82a4d5\" target=\"_blank\" rel=\"noreferrer noopener\">Descobreix el Bungalow Accessible<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--4\"><a class=\"wp-block-button__link has-blank-3-white-color has-blank-3-new-blue-2-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/my.matterport.com\/show\/?m=2iupqXkGbne\" target=\"_blank\" rel=\"noreferrer noopener\">Tour<img decoding=\"async\" width=\"35\" height=\"35\" class=\"wp-image-52140 lazyload\" style=\"--smush-placeholder-width: 35px; --smush-placeholder-aspect-ratio: 35\/35;width: 35px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/360-grados-e1717334095217.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Virtual <\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light wide-inner-container\"><img decoding=\"async\" width=\"2048\" height=\"1125\" class=\"wp-block-cover__image-background wp-image-19437 lazyload\" alt=\"\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1.jpg\" data-object-fit=\"cover\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1.jpg 2048w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-300x165.jpg 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-1024x563.jpg 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-1536x844.jpg 1536w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-900x494.jpg 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-320x176.jpg 320w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-240x132.jpg 240w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/alojamientos-1-1800x989.jpg 1800w\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1125;\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-blank-3-white-background-color has-background-dim-90 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h4 class=\"wp-block-heading alignwide has-blank-3-black-color has-text-color\">Allotjaments<\/h4>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-color\" style=\"color:#82a4d5\">Altres allotjaments que et poden interessar<\/h2>\n\n\n\n<style>\n@media only screen and (min-width: 0px) and (max-width: 380px){\n        #grid-items-block_fa054591c1cfc8de1f23ce4e2ecef99c.is-style-default [class*=\"grid-item\"] {\n            flex-basis: 100%;\n            width: 100%;\n        }\n\n        #grid-items-block_fa054591c1cfc8de1f23ce4e2ecef99c{\n            justify-content: center;\n        }\n    }\n@media only screen and (min-width: 381px) and (max-width: 799px){\n        #grid-items-block_fa054591c1cfc8de1f23ce4e2ecef99c.is-style-default [class*=\"grid-item\"] {\n            flex-basis: 48%;\n            width: 48%;\n        }\n\n    }\n@media only screen and (min-width: 800px){\n        #grid-items-block_fa054591c1cfc8de1f23ce4e2ecef99c [class*=\"grid-item\"] {\n            width: calc(100% * (1\/3) - 1%);\n            margin: calc(2% *(1\/4));\n        }\n        #grid-items-block_fa054591c1cfc8de1f23ce4e2ecef99c.is-style-dynamic [class*=\"grid-item\"]:hover{\n            width: calc(100% * (1\/2.25) - 1%);\n        }\n    }\n<\/style>\n<div class=\"wp-block-grid-items alignwide\">\n    <div id=\"grid-items-block_fa054591c1cfc8de1f23ce4e2ecef99c\" class=\"flex is-style-default\">\n                <a class=\"grid-item-24953\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-4-persones\/\">\n            <div class=\"inner-card\">\n                                                                <div id=\"thumbnail-19450\" class=\"thumbnail-card\">\n\n                                            <img decoding=\"async\" width=\"420\" height=\"270\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0765-420x270.jpg\" class=\"attachment-carousel-small size-carousel-small wp-post-image lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 420px; --smush-placeholder-aspect-ratio: 420\/270;\" \/>                                    <\/div>\n                <div class=\"content-card html-content\">\n                    <h4 class=\"has-blank-3-new-blue-1-color\">Mobil-Home 4 persones                                                                   <\/h4>\n                                            <p>Per les fam\u00edlies que busquen sobretot comoditat. Capacitat m\u00e0xima: 4 persones<\/p>\n                                    <\/div>\n            <\/div>\n\n\n        <\/a>\n                <a class=\"grid-item-24961\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-6-persones\/\">\n            <div class=\"inner-card\">\n                                                                <div id=\"thumbnail-19451\" class=\"thumbnail-card\">\n\n                                            <img decoding=\"async\" width=\"420\" height=\"270\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0245-420x270.jpg\" class=\"attachment-carousel-small size-carousel-small wp-post-image lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 420px; --smush-placeholder-aspect-ratio: 420\/270;\" \/>                                    <\/div>\n                <div class=\"content-card html-content\">\n                    <h4 class=\"has-blank-3-new-blue-1-color\">Mobil-Home 6 persones                                                                   <\/h4>\n                                            <p>Perqu\u00e8 tota la fam\u00edlia gaudeixi sense que els hi falti de res. Capacitat m\u00e0xima: 6 persones<\/p>\n                                    <\/div>\n            <\/div>\n\n\n        <\/a>\n            <\/div>\n<\/div>\n\n\n<\/div><\/div>\n\n\n\n<div id=\"block-popup-block_f3eef147511f535556e38f8a0cf55a6c\" class=\"wp-block-popup\" data-popup=\"popup-comparador\">\n<div class=\"popup-overlay\"><\/div>\n    <a class=\"close-popup-link icon-close link-ico-em\" href=\"javascript:void(0)\"><\/a>\n    <div class=\"content-popup\">\n        \n\n<div class=\"wp-block-group table-titles is-content-justification-right is-nowrap is-layout-flex wp-container-core-group-is-layout-fd526d70 wp-block-group-is-layout-flex\">\n<p class=\"has-text-align-center has-blank-3-white-color has-text-color has-background\" style=\"background-color:#86aee3\"><strong>BUNGALOW<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color has-background\" style=\"color:#5b574b;background-color:#f1f1f1\"><strong>MOBIL HOME<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-blank-3-white-color has-blank-3-darkblue-background-color has-text-color has-background\"><strong>GLAMPING<\/strong><\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-blank-3-blue-color\"><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\" data-type=\"page\" data-id=\"19449\">Bungalow Premium<\/a><\/mark><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-blank-3-blue-color\"><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-de-fusta\/\" data-type=\"page\" data-id=\"19447\">Bungalow Madera<\/a><\/mark><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-blank-3-blue-color\"><a href=\"https:\/\/www.campingdelmar.com\/alojamientos\/bungalow-premium-adaptado\/\" data-type=\"page\" data-id=\"34787\">Bungalow Accesible<\/a><\/mark><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/?page_id=46686\" data-type=\"page\" data-id=\"44894\">Bungalow Mediterrani<\/a><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0);color:#5b574b\" class=\"has-inline-color\"><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-6-persones\/\" data-type=\"page\" data-id=\"19451\">Mobil-Home 6<\/a><\/mark><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0);color:#5b574b\" class=\"has-inline-color\"><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-4-persones\/\" data-type=\"page\" data-id=\"19450\">Mobil-Home 4<\/a><\/mark><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/glamping-mar-2-persones\/\" data-type=\"page\" data-id=\"38848\">Glamping Mar 2<\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/glamping-mar-4-persones\/\" data-type=\"page\" data-id=\"38974\">Glamping Mar 4<\/a><\/td><\/tr><tr><td><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\" data-type=\"page\" data-id=\"19449\"><img decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-37576 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/100;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium.webp\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium.webp 1080w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium-300x200.webp 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium-1024x683.webp 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium-900x600.webp 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium-90x60.webp 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-premium-240x160.webp 240w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-de-fusta\/\" data-type=\"page\" data-id=\"19447\"><img decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-37569 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/100;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta.webp\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta.webp 1080w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta-300x200.webp 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta-1024x683.webp 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta-900x600.webp 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta-90x60.webp 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-fusta-240x160.webp 240w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/alojamientos\/bungalow-premium-adaptado\/\" data-type=\"page\" data-id=\"34787\"><img decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-37583 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/100;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible.webp\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible.webp 1080w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible-300x200.webp 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible-1024x683.webp 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible-900x600.webp 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible-90x60.webp 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bungalow-accesible-240x160.webp 240w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/?page_id=46686\" data-type=\"page\" data-id=\"44894\"><img decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-46634 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/100;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-scaled.jpg\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-scaled.jpg 2560w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-300x200.jpg 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-1024x683.jpg 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-1536x1024.jpg 1536w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-2048x1365.jpg 2048w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-900x600.jpg 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-90x60.jpg 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-240x160.jpg 240w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/15-de-mayo-de-2023-27-1800x1200.jpg 1800w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-6-persones\/\" data-type=\"page\" data-id=\"19451\"><img decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-37562 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/100;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1.webp\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1.webp 1080w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1-300x200.webp 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1-1024x683.webp 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1-900x600.webp 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1-90x60.webp 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-6-comparador-1-240x160.webp 240w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/mobil-home-4-persones\/\" data-type=\"page\" data-id=\"19450\"><img decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-37590 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/100;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador.webp\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador.webp 1080w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador-300x200.webp 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador-1024x683.webp 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador-900x600.webp 900w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador-90x60.webp 90w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/mh-4-comparador-240x160.webp 240w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/glamping-mar-2-persones\/\" data-type=\"page\" data-id=\"38848\"><img decoding=\"async\" width=\"150\" height=\"143\" class=\"wp-image-38877 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/143;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1.jpg\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1.jpg 2048w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-300x285.jpg 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-1024x975.jpg 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-1536x1462.jpg 1536w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-240x228.jpg 240w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-1800x1713.jpg 1800w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><td><a href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/glamping-mar-4-persones\/\" data-type=\"page\" data-id=\"38974\"><img decoding=\"async\" width=\"150\" height=\"143\" class=\"wp-image-39003 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/143;width: 150px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2.jpg\" alt=\"\" data-srcset=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2.jpg 2048w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2-300x285.jpg 300w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2-1024x975.jpg 1024w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2-1536x1462.jpg 1536w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2-240x228.jpg 240w, https:\/\/www.campingdelmar.com\/wp-content\/uploads\/img-5767-1-2-1800x1713.jpg 1800w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/td><\/tr><tr><td>Interior m<sup>2<\/sup><\/td><td>27m<sup>2<\/sup><\/td><td>27m<sup>2<\/sup><\/td><td>27m<sup>2<\/sup><\/td><td>27m<sup>2<\/sup><\/td><td>29m<sup>2<\/sup><\/td><td>21m<sup>2<\/sup><\/td><td>27m<sup>2<\/sup><\/td><td>27m<sup>2<\/sup><\/td><\/tr><tr><td>Terraza m<sup>2<\/sup><\/td><td>12m<sup>2<\/sup><\/td><td>12m<sup>2<\/sup><\/td><td>12m<sup>2<\/sup><\/td><td>12m<sup>2<\/sup><\/td><td>11m<sup>2<\/sup><\/td><td><\/td><td>12m<sup>2<\/sup><\/td><td>12m<sup>2<\/sup><\/td><\/tr><tr><td>Habitaciones<\/td><td>2<\/td><td>2<\/td><td>1<\/td><td>2<\/td><td>3<\/td><td>2<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>Capacidad de personas<\/td><td>6<\/td><td>6<\/td><td>4<\/td><td>6<\/td><td>6<\/td><td>4<\/td><td>2<\/td><td>4<\/td><\/tr><tr><td>Camas de matrimonio<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>Camas individuales<\/td><td>2<\/td><td>2<\/td><td>&#8211;<\/td><td>2<\/td><td>4<\/td><td>2<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td>Capacidad sof\u00e1-cama<\/td><td>2<\/td><td>2<\/td><td>2<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>Cuarto de ba\u00f1o<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Ducha<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>S\u00e1banas y toallas incluidas<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Nevera<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Congelador<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Microondas<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Cafetera<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Cocina<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Tostadora<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Aire Acondicionado<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Calefacci\u00f3n<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>TV<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Barbacoa<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Terraza<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Parking Veh\u00edculo<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>Mascotas permitidas<\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td>1 Ticket Wifi Gratis<\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"32\" height=\"32\" class=\"wp-image-37552 lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;width: 32px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/close.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td><img decoding=\"async\" width=\"33\" height=\"32\" class=\"wp-image-37544 lazyload\" style=\"--smush-placeholder-width: 33px; --smush-placeholder-aspect-ratio: 33\/32;width: 33px;\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/check.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><\/tbody><\/table><\/figure>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Pels amants del &#8220;tot incl\u00f2s&#8221;. Capacitat m\u00e0xima: 6 persones<\/p>\n","protected":false},"author":1,"featured_media":35416,"parent":24880,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-24921","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camping del Mar - Millor preu garantit! ????<\/title>\n<meta name=\"description\" content=\"C\u00e0mping petit i familiar a peu de platja a la costa de Barcelona amb piscina i animaci\u00f3 per a tota la fam\u00edlia! ????\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camping del Mar - Millor preu garantit! ????\" \/>\n<meta property=\"og:description\" content=\"C\u00e0mping petit i familiar a peu de platja a la costa de Barcelona amb piscina i animaci\u00f3 per a tota la fam\u00edlia! ????\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping del Mar\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T10:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\",\"name\":\"Camping del Mar - Millor preu garantit! ????\",\"isPartOf\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg\",\"datePublished\":\"2020-04-29T10:10:35+00:00\",\"dateModified\":\"2026-02-05T10:12:13+00:00\",\"description\":\"C\u00e0mping petit i familiar a peu de platja a la costa de Barcelona amb piscina i animaci\u00f3 per a tota la fam\u00edlia! ????\",\"breadcrumb\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#primaryimage\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg\",\"width\":2048,\"height\":1908},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.campingdelmar.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allotjaments\",\"item\":\"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bungalow Premium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#website\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/\",\"name\":\"Camping del Mar\",\"description\":\"Bungalow Park, Malgrat de Mar\",\"publisher\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campingdelmar.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#organization\",\"name\":\"Camping del Mar\",\"url\":\"https:\/\/www.campingdelmar.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"width\":619,\"height\":697,\"caption\":\"Camping del Mar\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camping del Mar - Millor preu garantit! ????","description":"C\u00e0mping petit i familiar a peu de platja a la costa de Barcelona amb piscina i animaci\u00f3 per a tota la fam\u00edlia! ????","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/","og_locale":"ca_ES","og_type":"article","og_title":"Camping del Mar - Millor preu garantit! ????","og_description":"C\u00e0mping petit i familiar a peu de platja a la costa de Barcelona amb piscina i animaci\u00f3 per a tota la fam\u00edlia! ????","og_url":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/","og_site_name":"Camping del Mar","article_modified_time":"2026-02-05T10:12:13+00:00","og_image":[{"width":2048,"height":1908,"url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"27 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/","url":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/","name":"Camping del Mar - Millor preu garantit! ????","isPartOf":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#primaryimage"},"image":{"@id":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg","datePublished":"2020-04-29T10:10:35+00:00","dateModified":"2026-02-05T10:12:13+00:00","description":"C\u00e0mping petit i familiar a peu de platja a la costa de Barcelona amb piscina i animaci\u00f3 per a tota la fam\u00edlia! ????","breadcrumb":{"@id":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#primaryimage","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/220801-estudio-fragil-camping-del-mar-0580jjjj.jpg","width":2048,"height":1908},{"@type":"BreadcrumbList","@id":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/bungalow-premium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.campingdelmar.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Allotjaments","item":"https:\/\/www.campingdelmar.com\/ca\/allotjaments\/"},{"@type":"ListItem","position":3,"name":"Bungalow Premium"}]},{"@type":"WebSite","@id":"https:\/\/www.campingdelmar.com\/ca\/#website","url":"https:\/\/www.campingdelmar.com\/ca\/","name":"Camping del Mar","description":"Bungalow Park, Malgrat de Mar","publisher":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campingdelmar.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.campingdelmar.com\/ca\/#organization","name":"Camping del Mar","url":"https:\/\/www.campingdelmar.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","width":619,"height":697,"caption":"Camping del Mar"},"image":{"@id":"https:\/\/www.campingdelmar.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/comments?post=24921"}],"version-history":[{"count":20,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24921\/revisions"}],"predecessor-version":[{"id":54745,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24921\/revisions\/54745"}],"up":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/pages\/24880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/media\/35416"}],"wp:attachment":[{"href":"https:\/\/www.campingdelmar.com\/ca\/wp-json\/wp\/v2\/media?parent=24921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}