{"id":25692,"date":"2020-05-13T10:31:22","date_gmt":"2020-05-13T08:31:22","guid":{"rendered":"https:\/\/www.campingdelmar.com\/2020\/unkategorisiert\/beste-zahlungsbedingungen\/"},"modified":"2020-05-13T10:31:22","modified_gmt":"2020-05-13T08:31:22","slug":"beste-zahlungsbedingungen","status":"publish","type":"post","link":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/","title":{"rendered":"Beste Zahlungsbedingungen"},"content":{"rendered":"\n<p>Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website sprechen.<\/p>\n<!-- fold.php -->\n\n<style>\n\n<\/style>\n<script>\n    $(document).ready(function() {\n\n\n    });\n\n<\/script>\n    \n    <div id=\"fold-list-block_5e7dd0b2e7d2a\" class=\"\">\n                <div class=\"fold-list-wrapper\">\n\n                                                <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-84\" name=\"faq-group\" checked>\n                <label for=\"faq-84\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/guarantee.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Garantiert bester Preis: <span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Wenn Sie vor der Buchung oder innerhalb von 24 Stunden nach Ihrer Buchung einen g\u00fcnstigeren Preis auf einer anderen Website finden, passen wir unseren Preis  an.<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-85\" name=\"faq-group\" checked>\n                <label for=\"faq-85\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/promocion.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Exklusive Angebote<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Sie finden  viele interessante  Angebote exklusiv auf unserer Website.<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-86\" name=\"faq-group\" checked>\n                <label for=\"faq-86\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/bill.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Ohne Extrakosten<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Sie zahlen keine Extrakosten oder Provisionen an Vermittler. In den Preisen auf unserer Website sind schon alle Geb\u00fchren enthalten. Somit entstehen f\u00fcr Sie keine zus\u00e4tzlichen Kosten bei Ihrer Ankunft. <\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-87\" name=\"faq-group\" checked>\n                <label for=\"faq-87\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/refresh.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Jederzeit aktualisierte Informationen<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Die Verf\u00fcgbarkeit f\u00fcr alle Unterk\u00fcnfte wird in Echtzeit angezeigt. Somit erhalten Sie Ihre Reisebest\u00e4tigung umgehend.<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-88\" name=\"faq-group\" checked>\n                <label for=\"faq-88\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/okay.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Sofortige Reise\u00e4nderungen und Stornierungen<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>: Alle \u00c4nderungen und Stornierungen sind einfach und umgehend. Sie k\u00f6nnen Ihre Reservierung bis zu 15 Tagen vor Ihrer Ankunft kostenlos \u00e4ndern oder stornieren (Ausser beim nicht erstattungsf\u00e4higen Tarif).<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-89\" name=\"faq-group\" checked>\n                <label for=\"faq-89\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/card.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Beste Zahlungsbedingungen<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Bei der Reservierung zahlen Sie 25% des Gesamtpreises und den Rest bei Ihrer Ankunft. (Ausser beim nicht erstattungsf\u00e4higen Tarif)<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-90\" name=\"faq-group\" checked>\n                <label for=\"faq-90\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/crecimiento.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Garantierter Upgrade<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Wenn die Verf\u00fcgbarkeit es zul\u00e4sst, geben wir Ihnen eine Unterkunft einer h\u00f6heren Kategorie ohne Kostenaufschlag.<\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-91\" name=\"faq-group\" checked>\n                <label for=\"faq-91\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/luggage.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Late-Out<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Wir hetzen Sie nicht. Wenn die Verf\u00fcgbarkeit es zul\u00e4sst, bieten wir Ihnen die M\u00f6glichkeit an Ihre Abreise v\u00f6llig kostenlos bis 17Uhr zu verl\u00e4ngern. Sollte der Late Check- Out nicht m\u00f6glich sein, bewahren wir Ihr Gep\u00e4ck selbstverst\u00e4ndlich bis zu Ihrer Abreise auf. <\/p>\n<\/div>\n                            <\/div>\n                        <div class=\"fold-inner\">\n                                                <input type=\"checkbox\" id=\"faq-92\" name=\"faq-group\" checked>\n                <label for=\"faq-92\"><img decoding=\"async\" class=\"label-img lazyload\" width=\"32px\" data-src=\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/password.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Datensicherheit<span class=\"icon-keyboard_arrow_left\"><\/span><\/label>\n                <div class=\"content-faq\"><p>Wir behandeln Ihre Daten mit maximaler Vertraulichkeit. Alle Informationen, die Sie auf unserer Website eingeben, sind sicher und f\u00fcr Dritte unzug\u00e4nglich.<\/p>\n<\/div>\n                            <\/div>\n                    <\/div>\n        \n    <\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[128],"tags":[],"class_list":["post-25692","post","type-post","status-publish","format-standard","hentry","category-vorteile-der-direkten-buchung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beste Zahlungsbedingungen - Camping del Mar<\/title>\n<meta name=\"description\" content=\"Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beste Zahlungsbedingungen - Camping del Mar\" \/>\n<meta property=\"og:description\" content=\"Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping del Mar\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-13T08:31:22+00:00\" \/>\n<meta name=\"author\" content=\"Camping\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camping\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\"},\"author\":{\"name\":\"Camping\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#\/schema\/person\/91978325dd78f0e0895f7576237a30ad\"},\"headline\":\"Beste Zahlungsbedingungen\",\"datePublished\":\"2020-05-13T08:31:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\"},\"wordCount\":29,\"publisher\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#organization\"},\"articleSection\":[\"Vorteile der direkten buchung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\",\"url\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\",\"name\":\"Beste Zahlungsbedingungen - Camping del Mar\",\"isPartOf\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#website\"},\"datePublished\":\"2020-05-13T08:31:22+00:00\",\"description\":\"Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website\",\"breadcrumb\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Der Beginn\",\"item\":\"https:\/\/www.campingdelmar.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beste Zahlungsbedingungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#website\",\"url\":\"https:\/\/www.campingdelmar.com\/de\/\",\"name\":\"Camping del Mar\",\"description\":\"Bungalow Park, Malgrat de Mar\",\"publisher\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campingdelmar.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#organization\",\"name\":\"Camping del Mar\",\"url\":\"https:\/\/www.campingdelmar.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"contentUrl\":\"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg\",\"width\":619,\"height\":697,\"caption\":\"Camping del Mar\"},\"image\":{\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#\/schema\/person\/91978325dd78f0e0895f7576237a30ad\",\"name\":\"Camping\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.campingdelmar.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8691028c1e072ccc5bcb1f4f053e69c3cc7d07268466f0a3cdd982373ea113ae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8691028c1e072ccc5bcb1f4f053e69c3cc7d07268466f0a3cdd982373ea113ae?s=96&d=mm&r=g\",\"caption\":\"Camping\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beste Zahlungsbedingungen - Camping del Mar","description":"Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/","og_locale":"de_DE","og_type":"article","og_title":"Beste Zahlungsbedingungen - Camping del Mar","og_description":"Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website","og_url":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/","og_site_name":"Camping del Mar","article_published_time":"2020-05-13T08:31:22+00:00","author":"Camping","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Camping"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/#article","isPartOf":{"@id":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/"},"author":{"name":"Camping","@id":"https:\/\/www.campingdelmar.com\/de\/#\/schema\/person\/91978325dd78f0e0895f7576237a30ad"},"headline":"Beste Zahlungsbedingungen","datePublished":"2020-05-13T08:31:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/"},"wordCount":29,"publisher":{"@id":"https:\/\/www.campingdelmar.com\/de\/#organization"},"articleSection":["Vorteile der direkten buchung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/","url":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/","name":"Beste Zahlungsbedingungen - Camping del Mar","isPartOf":{"@id":"https:\/\/www.campingdelmar.com\/de\/#website"},"datePublished":"2020-05-13T08:31:22+00:00","description":"Wir bevorzugen den Direktkontakt als \u00fcber Dritte zu verhandeln. Hier f\u00fchren wir Ihnen alle Gr\u00fcnde auf, die f\u00fcr eine Direktbuchung auf unserer Website","breadcrumb":{"@id":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.campingdelmar.com\/de\/2020\/vorteile-der-direkten-buchung\/beste-zahlungsbedingungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Der Beginn","item":"https:\/\/www.campingdelmar.com\/de\/"},{"@type":"ListItem","position":2,"name":"Beste Zahlungsbedingungen"}]},{"@type":"WebSite","@id":"https:\/\/www.campingdelmar.com\/de\/#website","url":"https:\/\/www.campingdelmar.com\/de\/","name":"Camping del Mar","description":"Bungalow Park, Malgrat de Mar","publisher":{"@id":"https:\/\/www.campingdelmar.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campingdelmar.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.campingdelmar.com\/de\/#organization","name":"Camping del Mar","url":"https:\/\/www.campingdelmar.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.campingdelmar.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","contentUrl":"https:\/\/www.campingdelmar.com\/wp-content\/uploads\/camping-del-mar-logo.jpg","width":619,"height":697,"caption":"Camping del Mar"},"image":{"@id":"https:\/\/www.campingdelmar.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.campingdelmar.com\/de\/#\/schema\/person\/91978325dd78f0e0895f7576237a30ad","name":"Camping","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.campingdelmar.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8691028c1e072ccc5bcb1f4f053e69c3cc7d07268466f0a3cdd982373ea113ae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8691028c1e072ccc5bcb1f4f053e69c3cc7d07268466f0a3cdd982373ea113ae?s=96&d=mm&r=g","caption":"Camping"}}]}},"_links":{"self":[{"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/posts\/25692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/comments?post=25692"}],"version-history":[{"count":1,"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/posts\/25692\/revisions"}],"predecessor-version":[{"id":25693,"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/posts\/25692\/revisions\/25693"}],"wp:attachment":[{"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/media?parent=25692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/categories?post=25692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campingdelmar.com\/de\/wp-json\/wp\/v2\/tags?post=25692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}